{"id":8127,"date":"2021-07-24T19:19:59","date_gmt":"2021-07-24T17:19:59","guid":{"rendered":"https:\/\/arqueoxarxa.colleccions.cat\/?post_type=objecte&#038;p=8127"},"modified":"2025-12-01T19:54:32","modified_gmt":"2025-12-01T18:54:32","slug":"mac-gir-041092","status":"publish","type":"objecte","link":"https:\/\/arqueoxarxa.colleccions.cat\/es\/objecte\/mac-gir-041092\/","title":{"rendered":"c\u00e0lat del taller de Fontscaldes"},"content":{"rendered":"","protected":false},"featured_media":5060,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"museu":[53],"objecte_destacat":[],"class_list":["post-8127","objecte","type-objecte","status-publish","has-post-thumbnail","hentry","museu-museu-darqueologia-de-catalunya-girona-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/objecte\/8127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/objecte"}],"about":[{"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/types\/objecte"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/media\/5060"}],"wp:attachment":[{"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/media?parent=8127"}],"wp:term":[{"taxonomy":"museu","embeddable":true,"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/museu?post=8127"},{"taxonomy":"objecte_destacat","embeddable":true,"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/objecte_destacat?post=8127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}