{"id":7776,"date":"2021-07-24T19:39:57","date_gmt":"2021-07-24T17:39:57","guid":{"rendered":"https:\/\/arqueoxarxa.colleccions.cat\/?post_type=objecte&#038;p=7776"},"modified":"2025-12-01T19:45:30","modified_gmt":"2025-12-01T18:45:30","slug":"mgecc-prov-g90-73","status":"publish","type":"objecte","link":"https:\/\/arqueoxarxa.colleccions.cat\/es\/objecte\/mgecc-prov-g90-73\/","title":{"rendered":"altar de cer\u00e0mica"},"content":{"rendered":"","protected":false},"featured_media":5377,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"museu":[47],"objecte_destacat":[],"class_list":["post-7776","objecte","type-objecte","status-publish","has-post-thumbnail","hentry","museu-museu-de-guissona-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/objecte\/7776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/objecte"}],"about":[{"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/types\/objecte"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/media\/5377"}],"wp:attachment":[{"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/media?parent=7776"}],"wp:term":[{"taxonomy":"museu","embeddable":true,"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/museu?post=7776"},{"taxonomy":"objecte_destacat","embeddable":true,"href":"https:\/\/arqueoxarxa.colleccions.cat\/es\/wp-json\/wp\/v2\/objecte_destacat?post=7776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}